{"id":8959,"date":"2026-05-12T11:00:16","date_gmt":"2026-05-12T09:00:16","guid":{"rendered":"https:\/\/www.schulzentrum-stetten-akm.de\/?p=8959"},"modified":"2026-05-12T11:02:52","modified_gmt":"2026-05-12T09:02:52","slug":"erster-parents-day-am-schulzentrum-stetten-a-k-m","status":"publish","type":"post","link":"https:\/\/www.schulzentrum-stetten-akm.de\/ro\/erster-parents-day-am-schulzentrum-stetten-a-k-m\/","title":{"rendered":"Erster \u201eParent\u2019s Day\u201c am Schulzentrum Stetten a.k.M."},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.schulzentrum-stetten-akm.de\/wp-content\/uploads\/2026\/05\/IMG_8514.heic\" alt=\"\" class=\"wp-image-8960\"\/><\/figure>\n\n\n\n<p>Am Donnerstag, den 07. Mai 2026, fand am Schulzentrum Stetten a.k.M. erstmals der \u201eParent\u2019s Day\u201c f\u00fcr alle Lernpartnerinnen und Lernpartner der Lernstufe 6 statt. Ziel der Veranstaltung war es, den Jugendlichen praxisnahe Einblicke in verschiedene Berufe zu erm\u00f6glichen und erste Ber\u00fchrungen mit der Berufswelt anzubahnen.<\/p>\n\n\n\n<p>Nach einer gemeinsamen Begr\u00fc\u00dfung im Kubus durch den Schulleiter Herr Dr. Probst starteten die Vortr\u00e4ge. In f\u00fcnf kurzen Gespr\u00e4chsrunden wechselten die Sch\u00fclerinnen und Sch\u00fcler zwischen den Angeboten und konnten unterschiedliche Berufe kennenlernen. Die Lernenden nutzten die Gelegenheit, Fragen zu stellen und erste Einblicke in die Arbeitswelt zu erhalten.<\/p>\n\n\n\n<p>Besonders wertvoll war dabei die Unterst\u00fctzung der Eltern und Erziehungsberechtigten, die den Sch\u00fclerinnen und Sch\u00fclern aus erster Hand von ihrem Berufsalltag, ihren Ausbildungswegen und pers\u00f6nlichen Erfahrungen berichteten. Die Vortr\u00e4ge wurden durch die Eltern abwechslungsreich und praxisnah gestaltet. Begleitend bearbeiteten die Sch\u00fclerinnen und Sch\u00fcler einen Arbeitsauftrag, der anschlie\u00dfend in den Lerngruppen besprochen wird.<\/p>\n\n\n\n<p>Der erste \u201eParent\u2019s Day\u201c am Schulzentrum zeigt, wie bedeutend die Zusammenarbeit zwischen Schule und Elternhaus f\u00fcr die Berufsorientierung der Jugendlichen ist.<\/p>\n\n\n\n<p>Ein herzlicher Dank gilt allen Eltern und Erziehungsberechtigten, die sich engagiert und den Jugendlichen ihre Berufe vorgestellt haben.<\/p>\n\n\n\n<p>Quelle: Julia M\u00fcller und Sarah Birkhofer<\/p>","protected":false},"excerpt":{"rendered":"<p>Am Donnerstag, den 07. Mai 2026, fand am Schulzentrum Stetten a.k.M. erstmals der \u201eParent\u2019s Day\u201c f\u00fcr alle Lernpartnerinnen und Lernpartner der Lernstufe 6 statt. Ziel der Veranstaltung war es, den &hellip; <\/p>","protected":false},"author":26,"featured_media":8960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44,1],"tags":[],"class_list":["post-8959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-berufsorientierung","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.schulzentrum-stetten-akm.de\/ro\/wp-json\/wp\/v2\/posts\/8959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schulzentrum-stetten-akm.de\/ro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schulzentrum-stetten-akm.de\/ro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schulzentrum-stetten-akm.de\/ro\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schulzentrum-stetten-akm.de\/ro\/wp-json\/wp\/v2\/comments?post=8959"}],"version-history":[{"count":2,"href":"https:\/\/www.schulzentrum-stetten-akm.de\/ro\/wp-json\/wp\/v2\/posts\/8959\/revisions"}],"predecessor-version":[{"id":8962,"href":"https:\/\/www.schulzentrum-stetten-akm.de\/ro\/wp-json\/wp\/v2\/posts\/8959\/revisions\/8962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schulzentrum-stetten-akm.de\/ro\/wp-json\/wp\/v2\/media\/8960"}],"wp:attachment":[{"href":"https:\/\/www.schulzentrum-stetten-akm.de\/ro\/wp-json\/wp\/v2\/media?parent=8959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schulzentrum-stetten-akm.de\/ro\/wp-json\/wp\/v2\/categories?post=8959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schulzentrum-stetten-akm.de\/ro\/wp-json\/wp\/v2\/tags?post=8959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}